{"id":22626,"date":"2023-04-01T10:56:54","date_gmt":"2023-04-01T08:56:54","guid":{"rendered":"https:\/\/new.astrea-apotheke.ch\/pollenalarm\/"},"modified":"2024-12-29T21:06:13","modified_gmt":"2024-12-29T19:06:13","slug":"alerte-aux-pollens","status":"publish","type":"post","link":"https:\/\/astrea-apotheke.ch\/fr\/alerte-aux-pollens\/","title":{"rendered":"Alerte aux pollens!"},"content":{"rendered":"<h1 style=\"font-size:51px;font-style:normal;font-weight:400;margin-bottom:var(--wp--preset--spacing--50)\" class=\"wp-block-post-title has-roboto-slab-font-family\">Alerte aux pollens!<\/h1>\r\n\r\n\r\n<p class=\"has-primary-color has-text-color has-roboto-font-family wp-block-paragraph\" style=\"margin-bottom: var(--wp--preset--spacing--20); font-size: 23px; line-height: 1.5;\"><em>Au printemps et au d\u00e9but de l\u2019\u00e9t\u00e9, la saison des allergies aux pollens bat son plein. Mais il existe diff\u00e9rentes possibilit\u00e9s pour se prot\u00e9ger des pollens et lutter contre les sympt\u00f4mes.<\/em><\/p>\r\n\r\n\r\n<div style=\"font-size:14px;text-transform:uppercase;margin-bottom:var(--wp--preset--spacing--60)\" class=\"wp-block-post-author\"><div class=\"wp-block-post-author__avatar\"><img alt='' src='https:\/\/secure.gravatar.com\/avatar\/a86d8eb75c259a13eed14bd5bf4454f493ceb520d8bda0a907a7636fd29d6e80?s=48&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/a86d8eb75c259a13eed14bd5bf4454f493ceb520d8bda0a907a7636fd29d6e80?s=96&#038;d=mm&#038;r=g 2x' class='avatar avatar-48 photo' height='48' width='48' \/><\/div><div class=\"wp-block-post-author__content\"><p class=\"wp-block-post-author__name\"><a href=\"https:\/\/astrea-apotheke.ch\/fr\/author\/juerg-lendemann\/\" target=\"_blank\">J\u00fcrg Lendenmann<\/a><\/p><p class=\"wp-block-post-author__bio\"><\/p><\/div><\/div>\r\n\r\n\r\n<div class=\"wp-block-group is-content-justification-left\" style=\"margin-top: var(--wp--preset--spacing--50); margin-bottom: var(--wp--preset--spacing--70);\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-container-core-group-is-layout-067db3cf wp-block-group-is-layout-constrained\"><\/div><\/div>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Les pollens de plantes comme le noisetier, l\u2019aulne, le fr\u00eane, le bouleau, le charme-houblon et l\u2019ambroisie sont en fait minuscules: avec seulement 15 \u00e0 30 milli\u00e8mes de millim\u00e8tres de diam\u00e8tre, il est impossible de les distinguer \u00e0 l\u2019\u0153il nu. S\u2019ils sont si petits, c\u2019est notamment parce qu\u2019ils proviennent de plantes an\u00e9mophiles: celles dont le pollen n\u2019est pas diss\u00e9min\u00e9 par l\u2019eau ou les animaux mais uniquement par le vent. Souvent, ils parcourent des centaines de kilom\u00e8tres avant de rencontrer une fleur femelle. La probabilit\u00e9 qu\u2019un grain de pollen transport\u00e9 par l\u2019air atterrisse sur une fleur femelle est infime par rapport aux chances de succ\u00e8s de la pollinisation par les insectes. Pour r\u00e9ussir \u00e0 se reproduire, les plantes an\u00e9mophiles produisent donc des quantit\u00e9s \u00e9normes de pollen: une \u00e9tamine de seigle contient environ 20\u2009000 grains de pollens, les chatons du noisetier ou un seul brin d\u2019herbe peuvent en lib\u00e9rer jusqu\u2019\u00e0 4 millions. Beaucoup de plantes an\u00e9mophiles comme les conif\u00e8res, le noisetier, l\u2019aulne, le bouleau et les gramin\u00e9es (poac\u00e9es) lib\u00e8rent leurs pollens avant le bourgeonnement des feuilles pour augmenter les chances de pollinisation. Quand il y a suffisamment de vent, les nu\u00e9es de pollens se d\u00e9posent sur les surfaces et forment un d\u00e9p\u00f4t jaune clair sur les vitres des voitures ou les fen\u00eatres.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Cible manqu\u00e9e mais grandes cons\u00e9quences<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Quand un grain de pollen atteint la corolle humide d\u2019une fleur femelle, il lib\u00e8re des prot\u00e9ines, des lipides et des glucides. Or, la m\u00eame chose se produit quand les grains de pollen rencontrent la muqueuse humide du nez ou la corn\u00e9e de l\u2019\u0153il. Si le syst\u00e8me immunitaire consid\u00e8re que les prot\u00e9ines ainsi lib\u00e9r\u00e9es sont \u00e9trang\u00e8res \u00e0 l\u2019organisme (antig\u00e8nes), les cellules plasmatiques produisent des substances pour se d\u00e9fendre (anticorps) contre cette agression: les immunoglobulines. Ces substances se fixent \u00e0 des globules blancs particuliers pr\u00e9sents dans le tissu conjonctif: les mastocytes. Ceux-ci renferment diff\u00e9rentes substances messag\u00e8res comme l\u2019histamine, les leucotri\u00e8nes, la s\u00e9rotonine et les prostaglandines, qu\u2019ils peuvent lib\u00e9rer en cas de contact r\u00e9p\u00e9t\u00e9. Elles agissent \u00e0 de multiples niveaux: elles dilatent rapidement les vaisseaux, rendent leur paroi plus perm\u00e9able, stimulent les nerfs et augmentent la production de mucus. Ce qui se traduit par les sympt\u00f4mes bien connus du rhume des foins (\u00e9galement appel\u00e9 allergie au pollen, pollinose ou rhinite allergique): d\u00e9mangeaisons et rougeurs oculaires, larmoiements, \u00e9ternuements, nez qui coule ou nez bouch\u00e9, envie de tousser, sensation d\u2019oreilles bouch\u00e9es et difficult\u00e9s respiratoires lors d\u2019un effort physique.<\/p>\r\n\r\n\r\n\r\n<div class=\"wp-block-group is-style-default\" style=\"border-radius: 72px; margin-top: var(--wp--preset--spacing--30); margin-bottom: var(--wp--preset--spacing--80);\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\r\n<blockquote class=\"wp-block-quote is-style-default has-primary-color has-text-color is-layout-flow wp-block-quote-is-layout-flow\" style=\"font-size: 16px; font-style: normal; font-weight: 600;\">\r\n<p class=\"has-roboto-slab-font-family has-normal-font-size wp-block-paragraph\" style=\"margin-top: var(--wp--preset--spacing--20); margin-right: var(--wp--preset--spacing--80); margin-bottom: 0; line-height: 1.5;\">L\u2019allergie au pollen touche <br \/>20\u2009% des Suisses.<\/p>\r\n<\/blockquote>\r\n<\/div><\/div>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Toujours plus d\u2019allergies au pollen<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Une vingtaine d\u2019esp\u00e8ces de plantes seulement sont responsables des allergies au pollen. Ce sont toutes des plantes an\u00e9mophiles, en sachant que les conif\u00e8res sont d\u00e9pourvus de substances allerg\u00e8nes. Le rhume des foins peut aussi \u00eatre d\u00e9clench\u00e9 par les pollens de gramin\u00e9es et de certaines fines herbes comme l\u2019armoise commune (Artemisia vulgaris) et l\u2019ambroisie \u00e0 feuilles d\u2019armoise (Artemisia artemisiifolia). La plupart des personnes allergiques \u00e0 un type de pollen r\u00e9agissent aussi aux pollens de plantes apparent\u00e9es. 70\u2009% des victimes du rhume des foins sont seulement allergiques aux pollens de gramin\u00e9es et de c\u00e9r\u00e9ales. La premi\u00e8re grande \u00e9tude \u00e9pid\u00e9miologique sur le rhume des foins en Suisse remonte \u00e0 1926, rappelle le Prof. Brunello W\u00fcthrich. \u00c0 l\u2019\u00e9poque, la fr\u00e9quence du rhume des foins \u00e9tait d\u2019environ 0,8\u2009%. 70 ans plus tard, il touche 20\u2009% des Suisses et repr\u00e9sente l\u2019allergie la plus fr\u00e9quente sous nos latitudes. Diff\u00e9rents facteurs expliquent cette augmentation impressionnante: d\u2019une part le changement climatique, car les temp\u00e9ratures plus \u00e9lev\u00e9es entra\u00eenent une production de pollens plus importante chez les plantes responsables des allergies. D\u2019autre part la pollution de l\u2019air, qui peut renforcer l\u2019action des allerg\u00e8nes. De plus, l\u2019exc\u00e8s d\u2019hygi\u00e8ne fait que le syst\u00e8me immunitaire a de plus en plus de mal \u00e0 se d\u00e9velopper de mani\u00e8re optimale. Les conditions m\u00e9t\u00e9o et le lieu influencent aussi l\u2019intensit\u00e9 des sympt\u00f4mes: la pluie offre un peu de r\u00e9pit aux victimes du rhume des foins. Dans les villes, la concentration en pollens est plus \u00e9lev\u00e9e le soir, \u00e0 la campagne, plut\u00f4t le matin.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Les possibilit\u00e9s de traitement<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">On pourrait simplement s\u2019en tenir \u00e0 cette lapalissade: \u00abSans allerg\u00e8nes, pas d\u2019allergie\u00bb. Mais quand des milliards de pollens sont pr\u00e9sents dans l\u2019air, difficile d\u2019\u00e9viter le contact. 10 \u00e0 50 grains de pollens par m\u00e8tre cube suffisent pour d\u00e9clencher une r\u00e9action allergique. Les pharmacies sont souvent le premier interlocuteur face aux sympt\u00f4mes, qui peuvent \u00eatre att\u00e9nu\u00e9s gr\u00e2ce \u00e0 des m\u00e9dicaments comme les antihistaminiques. Le m\u00e9decin de famille proc\u00e9dera \u00e0 des examens compl\u00e9mentaires. Il cherchera aussi \u00e0 savoir si une intol\u00e9rance alimentaire vient s\u2019ajouter aux sympt\u00f4mes du rhume des foins. Si n\u00e9cessaire, il prescrira un m\u00e9dicament qui inhibe la r\u00e9action allergique. La cause de l\u2019allergie peut \u00eatre combattue \u00e0 l\u2019aide d\u2019une s\u00e9rie d\u2019injections \u2013 hyposensibilisation, d\u00e9sensibilisation ou immunoth\u00e9rapie sp\u00e9cifique (ITS) \u2013 r\u00e9alis\u00e9es chez le m\u00e9decin de famille ou le dermatologue. Ce traitement s\u2019\u00e9tend sur au moins trois ans. Avant cela, les allerg\u00e8nes doivent \u00eatre d\u00e9termin\u00e9s \u00e0 l\u2019aide de \u00abprick tests\u00bb (tests cutan\u00e9s). Outre cette immunoth\u00e9rapie, qui consiste \u00e0 injecter les allerg\u00e8nes sous la peau, il est aussi possible de se d\u00e9sensibiliser en les appliquant sous la langue ou (en cas d\u2019allergie aux gramin\u00e9es) en avalant un comprim\u00e9. Les allergies au pollen ne doivent pas \u00eatre prises \u00e0 la l\u00e9g\u00e8re, car elles peuvent \u00e9voluer vers l\u2019asthme chronique.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">R\u00e9actions crois\u00e9es<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">La plupart des personnes touch\u00e9es r\u00e9agissent aussi au pollen de plantes apparent\u00e9es ainsi qu\u2019\u00e0 certains aliments pr\u00e9sentant des allerg\u00e8nes\/prot\u00e9ines proches de ceux qui d\u00e9clenchent le rhume des foins. Aha! Centre d\u2019Allergie Suisse met en garde contre les r\u00e9actions crois\u00e9es connues:<\/p>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>Pollens de bouleau \u2013 noisette, noix commune, amande, pomme, cerise, p\u00eache, kiwi, carotte, c\u00e9leri<\/li>\r\n\r\n\r\n\r\n<li>Pollens de gramin\u00e9es \u2013 tomate, melon, arachide<\/li>\r\n\r\n\r\n\r\n<li>Pollens d\u2019armoise \u2013 c\u00e9leri, carotte, fenouil, panais, anis, aneth, cumin, coriandre, poivron, persil, poivre, graines de tournesol, camomille<\/li>\r\n\r\n\r\n\r\n<li>Pollens d\u2019ambroisie \u2013 banane, melon, concombre<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9fba3e33 wp-block-columns-is-layout-flex\" style=\"margin-top: 60px; margin-bottom: 50px;\">\r\n<div class=\"wp-block-column has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"background-color: #f1f2f4; flex-basis: 800px; padding: var(--wp--preset--spacing--70);\">\r\n<h2 class=\"wp-block-heading\" style=\"margin-top: var(--wp--preset--spacing--20); margin-bottom: var(--wp--preset--spacing--50); margin-left: 0; font-size: 23px;\"><strong><strong>Pour vous prot\u00e9ger des pollens<\/strong><\/strong><\/h2>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>Pendant la saison pollinique, a\u00e9rez seulement bri\u00e8vement, par intermittence, et ne restez pas longtemps en plein air quand le temps est beau, sec et venteux.<\/li>\r\n\r\n\r\n\r\n<li>Passez l\u2019aspirateur tous les jours avec un aspirateur dot\u00e9 d\u2019un filtre HEPA ou un mod\u00e8le sans filtre certifi\u00e9.<\/li>\r\n\r\n\r\n\r\n<li>Nettoyez r\u00e9guli\u00e8rement tapis et meubles.<\/li>\r\n\r\n\r\n\r\n<li>Faites installer et entretenir r\u00e9guli\u00e8rement des filtres anti-pollen dans la voiture.<\/li>\r\n\r\n\r\n\r\n<li>Portez des lunettes de soleil \u00e0 l\u2019ext\u00e9rieur.<\/li>\r\n\r\n\r\n\r\n<li>Lavez-vous les cheveux le soir; d\u00e9shabillez-vous et laissez les v\u00eatements port\u00e9s hors de la chambre \u00e0 coucher.<\/li>\r\n\r\n\r\n\r\n<li>Ne mettez pas votre linge \u00e0 s\u00e9cher en plein air.<\/li>\r\n\r\n\r\n\r\n<li>Rincez-vous le nez matin et soir avec un spray \u00e0 l\u2019eau de mer ou du s\u00e9rum physiologique.<\/li>\r\n\r\n\r\n\r\n<li>Portez un masque chirurgical ou avec un filtre anti-pollen.<\/li>\r\n\r\n\r\n\r\n<li>Adaptez vos activit\u00e9s en plein air aux concentrations polliniques.<\/li>\r\n\r\n\r\n\r\n<li>V\u00e9rifiez les concentrations polliniques pour choisir votre destination de vacances.<\/li>\r\n\r\n\r\n\r\n<li>Les pollens sont beaucoup moins concentr\u00e9s \u00e0 la mer ou \u00e0 une altitude sup\u00e9rieure \u00e0 1500 m\u00e8tres.<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Retrouvez plus d\u2019informations et de conseils sur www.aha.ch. Vous trouverez des donn\u00e9es pr\u00e9cises sur les concentrations polliniques en Suisse sur le site Internet de la fondation aha! <a href=\"https:\/\/pollenetallergie.ch\" target=\"_blank\" rel=\"noreferrer noopener\">pollenetallergie.ch<\/a> ou sur l\u2019appli \u00abPollen-News\u00bb.<\/p>\r\n<\/div>\r\n<\/div>\r\n\r\n\r\n","protected":false},"excerpt":{"rendered":"<p>Au printemps et au d\u00e9but de l\u2019\u00e9t\u00e9, la saison des  [&#8230;]<\/p>\n","protected":false},"author":20,"featured_media":20171,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[774],"tags":[],"class_list":["post-22626","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-systeme-immunitaire-allergies"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alerte aux pollens! - Astrea Aptheke<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/astrea-apotheke.ch\/fr\/alerte-aux-pollens\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alerte aux pollens! - Astrea Aptheke\" \/>\n<meta property=\"og:description\" content=\"Au printemps et au d\u00e9but de l\u2019\u00e9t\u00e9, la saison des [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/astrea-apotheke.ch\/fr\/alerte-aux-pollens\/\" \/>\n<meta property=\"og:site_name\" content=\"Astrea Aptheke\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-01T08:56:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-29T19:06:13+00:00\" \/>\n<meta name=\"author\" content=\"J\u00fcrg Lendenmann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"J\u00fcrg Lendenmann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/astrea-apotheke.ch\\\/fr\\\/alerte-aux-pollens\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astrea-apotheke.ch\\\/fr\\\/alerte-aux-pollens\\\/\"},\"author\":{\"name\":\"J\u00fcrg Lendenmann\",\"@id\":\"https:\\\/\\\/astrea-apotheke.ch\\\/fr\\\/#\\\/schema\\\/person\\\/ce803b8abbd8e46b197a1320a460b8d6\"},\"headline\":\"Alerte aux pollens!\",\"datePublished\":\"2023-04-01T08:56:54+00:00\",\"dateModified\":\"2024-12-29T19:06:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/astrea-apotheke.ch\\\/fr\\\/alerte-aux-pollens\\\/\"},\"wordCount\":1351,\"publisher\":{\"@id\":\"https:\\\/\\\/astrea-apotheke.ch\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/astrea-apotheke.ch\\\/fr\\\/alerte-aux-pollens\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Syst\u00e8me immunitaire, allergies\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/astrea-apotheke.ch\\\/fr\\\/alerte-aux-pollens\\\/\",\"url\":\"https:\\\/\\\/astrea-apotheke.ch\\\/fr\\\/alerte-aux-pollens\\\/\",\"name\":\"Alerte aux pollens! - Astrea Aptheke\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astrea-apotheke.ch\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/astrea-apotheke.ch\\\/fr\\\/alerte-aux-pollens\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/astrea-apotheke.ch\\\/fr\\\/alerte-aux-pollens\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2023-04-01T08:56:54+00:00\",\"dateModified\":\"2024-12-29T19:06:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/astrea-apotheke.ch\\\/fr\\\/alerte-aux-pollens\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/astrea-apotheke.ch\\\/fr\\\/alerte-aux-pollens\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/astrea-apotheke.ch\\\/fr\\\/alerte-aux-pollens\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/astrea-apotheke.ch\\\/fr\\\/alerte-aux-pollens\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/astrea-apotheke.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alerte aux pollens!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/astrea-apotheke.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/astrea-apotheke.ch\\\/fr\\\/\",\"name\":\"astrea Bulletin\",\"description\":\"Gesundheitsmagazin\",\"publisher\":{\"@id\":\"https:\\\/\\\/astrea-apotheke.ch\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/astrea-apotheke.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/astrea-apotheke.ch\\\/fr\\\/#organization\",\"name\":\"astrea Bulletin\",\"url\":\"https:\\\/\\\/astrea-apotheke.ch\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/astrea-apotheke.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/apotheke.astrea-bulletin.ch\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Logo_Astrea-Bulletin_RGB.jpg\",\"contentUrl\":\"http:\\\/\\\/apotheke.astrea-bulletin.ch\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Logo_Astrea-Bulletin_RGB.jpg\",\"width\":1429,\"height\":560,\"caption\":\"astrea Bulletin\"},\"image\":{\"@id\":\"https:\\\/\\\/astrea-apotheke.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/astrea-apotheke.ch\\\/fr\\\/#\\\/schema\\\/person\\\/ce803b8abbd8e46b197a1320a460b8d6\",\"name\":\"J\u00fcrg Lendenmann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a86d8eb75c259a13eed14bd5bf4454f493ceb520d8bda0a907a7636fd29d6e80?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a86d8eb75c259a13eed14bd5bf4454f493ceb520d8bda0a907a7636fd29d6e80?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a86d8eb75c259a13eed14bd5bf4454f493ceb520d8bda0a907a7636fd29d6e80?s=96&d=mm&r=g\",\"caption\":\"J\u00fcrg Lendenmann\"},\"url\":\"https:\\\/\\\/astrea-apotheke.ch\\\/fr\\\/author\\\/juerg-lendemann\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alerte aux pollens! - Astrea Aptheke","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/astrea-apotheke.ch\/fr\/alerte-aux-pollens\/","og_locale":"fr_FR","og_type":"article","og_title":"Alerte aux pollens! - Astrea Aptheke","og_description":"Au printemps et au d\u00e9but de l\u2019\u00e9t\u00e9, la saison des [...]","og_url":"https:\/\/astrea-apotheke.ch\/fr\/alerte-aux-pollens\/","og_site_name":"Astrea Aptheke","article_published_time":"2023-04-01T08:56:54+00:00","article_modified_time":"2024-12-29T19:06:13+00:00","author":"J\u00fcrg Lendenmann","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"J\u00fcrg Lendenmann","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/astrea-apotheke.ch\/fr\/alerte-aux-pollens\/#article","isPartOf":{"@id":"https:\/\/astrea-apotheke.ch\/fr\/alerte-aux-pollens\/"},"author":{"name":"J\u00fcrg Lendenmann","@id":"https:\/\/astrea-apotheke.ch\/fr\/#\/schema\/person\/ce803b8abbd8e46b197a1320a460b8d6"},"headline":"Alerte aux pollens!","datePublished":"2023-04-01T08:56:54+00:00","dateModified":"2024-12-29T19:06:13+00:00","mainEntityOfPage":{"@id":"https:\/\/astrea-apotheke.ch\/fr\/alerte-aux-pollens\/"},"wordCount":1351,"publisher":{"@id":"https:\/\/astrea-apotheke.ch\/fr\/#organization"},"image":{"@id":"https:\/\/astrea-apotheke.ch\/fr\/alerte-aux-pollens\/#primaryimage"},"thumbnailUrl":"","articleSection":["Syst\u00e8me immunitaire, allergies"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/astrea-apotheke.ch\/fr\/alerte-aux-pollens\/","url":"https:\/\/astrea-apotheke.ch\/fr\/alerte-aux-pollens\/","name":"Alerte aux pollens! - Astrea Aptheke","isPartOf":{"@id":"https:\/\/astrea-apotheke.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/astrea-apotheke.ch\/fr\/alerte-aux-pollens\/#primaryimage"},"image":{"@id":"https:\/\/astrea-apotheke.ch\/fr\/alerte-aux-pollens\/#primaryimage"},"thumbnailUrl":"","datePublished":"2023-04-01T08:56:54+00:00","dateModified":"2024-12-29T19:06:13+00:00","breadcrumb":{"@id":"https:\/\/astrea-apotheke.ch\/fr\/alerte-aux-pollens\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/astrea-apotheke.ch\/fr\/alerte-aux-pollens\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/astrea-apotheke.ch\/fr\/alerte-aux-pollens\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/astrea-apotheke.ch\/fr\/alerte-aux-pollens\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/astrea-apotheke.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Alerte aux pollens!"}]},{"@type":"WebSite","@id":"https:\/\/astrea-apotheke.ch\/fr\/#website","url":"https:\/\/astrea-apotheke.ch\/fr\/","name":"astrea Bulletin","description":"Gesundheitsmagazin","publisher":{"@id":"https:\/\/astrea-apotheke.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/astrea-apotheke.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/astrea-apotheke.ch\/fr\/#organization","name":"astrea Bulletin","url":"https:\/\/astrea-apotheke.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/astrea-apotheke.ch\/fr\/#\/schema\/logo\/image\/","url":"http:\/\/apotheke.astrea-bulletin.ch\/wp-content\/uploads\/2024\/08\/Logo_Astrea-Bulletin_RGB.jpg","contentUrl":"http:\/\/apotheke.astrea-bulletin.ch\/wp-content\/uploads\/2024\/08\/Logo_Astrea-Bulletin_RGB.jpg","width":1429,"height":560,"caption":"astrea Bulletin"},"image":{"@id":"https:\/\/astrea-apotheke.ch\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/astrea-apotheke.ch\/fr\/#\/schema\/person\/ce803b8abbd8e46b197a1320a460b8d6","name":"J\u00fcrg Lendenmann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a86d8eb75c259a13eed14bd5bf4454f493ceb520d8bda0a907a7636fd29d6e80?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a86d8eb75c259a13eed14bd5bf4454f493ceb520d8bda0a907a7636fd29d6e80?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a86d8eb75c259a13eed14bd5bf4454f493ceb520d8bda0a907a7636fd29d6e80?s=96&d=mm&r=g","caption":"J\u00fcrg Lendenmann"},"url":"https:\/\/astrea-apotheke.ch\/fr\/author\/juerg-lendemann\/"}]}},"_links":{"self":[{"href":"https:\/\/astrea-apotheke.ch\/fr\/wp-json\/wp\/v2\/posts\/22626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/astrea-apotheke.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/astrea-apotheke.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/astrea-apotheke.ch\/fr\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/astrea-apotheke.ch\/fr\/wp-json\/wp\/v2\/comments?post=22626"}],"version-history":[{"count":2,"href":"https:\/\/astrea-apotheke.ch\/fr\/wp-json\/wp\/v2\/posts\/22626\/revisions"}],"predecessor-version":[{"id":31333,"href":"https:\/\/astrea-apotheke.ch\/fr\/wp-json\/wp\/v2\/posts\/22626\/revisions\/31333"}],"wp:attachment":[{"href":"https:\/\/astrea-apotheke.ch\/fr\/wp-json\/wp\/v2\/media?parent=22626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/astrea-apotheke.ch\/fr\/wp-json\/wp\/v2\/categories?post=22626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/astrea-apotheke.ch\/fr\/wp-json\/wp\/v2\/tags?post=22626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}